{"id":1213,"date":"2018-10-24T13:14:53","date_gmt":"2018-10-24T13:14:53","guid":{"rendered":"https:\/\/www.otto.de\/partnerprogramm\/?p=1213"},"modified":"2018-10-24T13:14:53","modified_gmt":"2018-10-24T13:14:53","slug":"voice-search-grosser-trend-nichts-dahinter","status":"publish","type":"post","link":"https:\/\/www.otto.de\/partnerprogramm\/voice-search-grosser-trend-nichts-dahinter\/","title":{"rendered":"Voice Search: Gro\u00dfer Trend, nichts dahinter?"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Die Suche \u00fcber Spracheingaben soll das n\u00e4chste gro\u00dfe Ding sein. Doch wie viel ist an dieser Annahme dran? <strong>Johann von H\u00fclsen<\/strong> stellt auf <a href=\"https:\/\/wngmn.de\/blog\/seo\/voice-search-grosser-trend-den-keiner-nutzt\/\" target=\"_blank\" rel=\"nofollow\"><strong>wngmn.de<\/strong><\/a> eine \u00dcbersicht zum Ist-Zustand in Deutschland dar und analysiert wof\u00fcr die Spracheingabe genutzt wird. Seine Ergebnisse zeigen u.a. dass 90% der Spracheingaben gar keine Suchen sind. Mehr dazu im Artikel.<\/p>\n<p>Quelle:\u00a0<a href=\"https:\/\/wngmn.de\/blog\/seo\/voice-search-grosser-trend-den-keiner-nutzt\/\" target=\"_blank\" rel=\"nofollow\">https:\/\/wngmn.de\/blog\/seo\/voice-search-grosser-trend-den-keiner-nutzt\/<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Die Suche \u00fcber Spracheingaben soll das n\u00e4chste gro\u00dfe Ding sein. Doch wie viel ist an dieser Annahme dran? Johann von H\u00fclsen stellt auf wngmn.de eine \u00dcbersicht zum Ist-Zustand in Deutschland dar und analysiert wof\u00fcr die Spracheingabe genutzt wird. Seine Ergebnisse zeigen u.a. dass 90% der Spracheingaben gar keine Suchen sind. Mehr dazu im Artikel. Quelle:\u00a0https:\/\/wngmn.de\/blog\/seo\/voice-search-grosser-trend-den-keiner-nutzt\/[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":7,"featured_media":1214,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"template-news.php","format":"standard","meta":{"footnotes":""},"categories":[1,4,6,8],"tags":[],"class_list":["post-1213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-einsteiger","category-fortgeschritten","category-news","category-seo","category-1","category-4","category-6","category-8","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Voice Search: Gro\u00dfer Trend, nichts dahinter? - OTTO Affiliate<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.otto.de\/partnerprogramm\/voice-search-grosser-trend-nichts-dahinter\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Voice Search: Gro\u00dfer Trend, nichts dahinter? - OTTO Affiliate\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]Die Suche \u00fcber Spracheingaben soll das n\u00e4chste gro\u00dfe Ding sein. Doch wie viel ist an dieser Annahme dran? Johann von H\u00fclsen stellt auf wngmn.de eine \u00dcbersicht zum Ist-Zustand in Deutschland dar und analysiert wof\u00fcr die Spracheingabe genutzt wird. Seine Ergebnisse zeigen u.a. dass 90% der Spracheingaben gar keine Suchen sind. Mehr dazu im Artikel. Quelle:\u00a0https:\/\/wngmn.de\/blog\/seo\/voice-search-grosser-trend-den-keiner-nutzt\/[\/vc_column_text][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.otto.de\/partnerprogramm\/voice-search-grosser-trend-nichts-dahinter\/\" \/>\n<meta property=\"og:site_name\" content=\"OTTO Affiliate\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-24T13:14:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.otto.de\/partnerprogramm\/app\/uploads\/2018\/10\/pexels-photo-1072851.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/voice-search-grosser-trend-nichts-dahinter\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/voice-search-grosser-trend-nichts-dahinter\\\/\"},\"author\":{\"name\":\"Redaktion\",\"@id\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/#\\\/schema\\\/person\\\/4c161909c66819493f845b52073d03b3\"},\"headline\":\"Voice Search: Gro\u00dfer Trend, nichts dahinter?\",\"datePublished\":\"2018-10-24T13:14:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/voice-search-grosser-trend-nichts-dahinter\\\/\"},\"wordCount\":87,\"image\":{\"@id\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/voice-search-grosser-trend-nichts-dahinter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/app\\\/uploads\\\/2018\\\/10\\\/pexels-photo-1072851.jpeg\",\"articleSection\":[\"Einsteiger\",\"Fortgeschritten\",\"News\",\"SEO\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/voice-search-grosser-trend-nichts-dahinter\\\/\",\"url\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/voice-search-grosser-trend-nichts-dahinter\\\/\",\"name\":\"Voice Search: Gro\u00dfer Trend, nichts dahinter? - OTTO Affiliate\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/voice-search-grosser-trend-nichts-dahinter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/voice-search-grosser-trend-nichts-dahinter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/app\\\/uploads\\\/2018\\\/10\\\/pexels-photo-1072851.jpeg\",\"datePublished\":\"2018-10-24T13:14:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/#\\\/schema\\\/person\\\/4c161909c66819493f845b52073d03b3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/voice-search-grosser-trend-nichts-dahinter\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/voice-search-grosser-trend-nichts-dahinter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/voice-search-grosser-trend-nichts-dahinter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/app\\\/uploads\\\/2018\\\/10\\\/pexels-photo-1072851.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/app\\\/uploads\\\/2018\\\/10\\\/pexels-photo-1072851.jpeg\",\"width\":640,\"height\":426},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/voice-search-grosser-trend-nichts-dahinter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/edit.otto-partnerprogramm.de\\\/partnerprogramm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Voice Search: Gro\u00dfer Trend, nichts dahinter?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/#website\",\"url\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/\",\"name\":\"OTTO Affiliate\",\"description\":\"Das OTTO Partnerprogramm\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/#\\\/schema\\\/person\\\/4c161909c66819493f845b52073d03b3\",\"name\":\"Redaktion\",\"url\":\"https:\\\/\\\/www.otto.de\\\/partnerprogramm\\\/author\\\/redaktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Voice Search: Gro\u00dfer Trend, nichts dahinter? - OTTO Affiliate","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.otto.de\/partnerprogramm\/voice-search-grosser-trend-nichts-dahinter\/","og_locale":"de_DE","og_type":"article","og_title":"Voice Search: Gro\u00dfer Trend, nichts dahinter? - OTTO Affiliate","og_description":"[vc_row][vc_column][vc_column_text]Die Suche \u00fcber Spracheingaben soll das n\u00e4chste gro\u00dfe Ding sein. Doch wie viel ist an dieser Annahme dran? Johann von H\u00fclsen stellt auf wngmn.de eine \u00dcbersicht zum Ist-Zustand in Deutschland dar und analysiert wof\u00fcr die Spracheingabe genutzt wird. Seine Ergebnisse zeigen u.a. dass 90% der Spracheingaben gar keine Suchen sind. Mehr dazu im Artikel. Quelle:\u00a0https:\/\/wngmn.de\/blog\/seo\/voice-search-grosser-trend-den-keiner-nutzt\/[\/vc_column_text][\/vc_column][\/vc_row]","og_url":"https:\/\/www.otto.de\/partnerprogramm\/voice-search-grosser-trend-nichts-dahinter\/","og_site_name":"OTTO Affiliate","article_published_time":"2018-10-24T13:14:53+00:00","og_image":[{"width":640,"height":426,"url":"https:\/\/www.otto.de\/partnerprogramm\/app\/uploads\/2018\/10\/pexels-photo-1072851.jpeg","type":"image\/jpeg"}],"author":"Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redaktion"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.otto.de\/partnerprogramm\/voice-search-grosser-trend-nichts-dahinter\/#article","isPartOf":{"@id":"https:\/\/www.otto.de\/partnerprogramm\/voice-search-grosser-trend-nichts-dahinter\/"},"author":{"name":"Redaktion","@id":"https:\/\/www.otto.de\/partnerprogramm\/#\/schema\/person\/4c161909c66819493f845b52073d03b3"},"headline":"Voice Search: Gro\u00dfer Trend, nichts dahinter?","datePublished":"2018-10-24T13:14:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.otto.de\/partnerprogramm\/voice-search-grosser-trend-nichts-dahinter\/"},"wordCount":87,"image":{"@id":"https:\/\/www.otto.de\/partnerprogramm\/voice-search-grosser-trend-nichts-dahinter\/#primaryimage"},"thumbnailUrl":"https:\/\/www.otto.de\/partnerprogramm\/app\/uploads\/2018\/10\/pexels-photo-1072851.jpeg","articleSection":["Einsteiger","Fortgeschritten","News","SEO"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.otto.de\/partnerprogramm\/voice-search-grosser-trend-nichts-dahinter\/","url":"https:\/\/www.otto.de\/partnerprogramm\/voice-search-grosser-trend-nichts-dahinter\/","name":"Voice Search: Gro\u00dfer Trend, nichts dahinter? - OTTO Affiliate","isPartOf":{"@id":"https:\/\/www.otto.de\/partnerprogramm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.otto.de\/partnerprogramm\/voice-search-grosser-trend-nichts-dahinter\/#primaryimage"},"image":{"@id":"https:\/\/www.otto.de\/partnerprogramm\/voice-search-grosser-trend-nichts-dahinter\/#primaryimage"},"thumbnailUrl":"https:\/\/www.otto.de\/partnerprogramm\/app\/uploads\/2018\/10\/pexels-photo-1072851.jpeg","datePublished":"2018-10-24T13:14:53+00:00","author":{"@id":"https:\/\/www.otto.de\/partnerprogramm\/#\/schema\/person\/4c161909c66819493f845b52073d03b3"},"breadcrumb":{"@id":"https:\/\/www.otto.de\/partnerprogramm\/voice-search-grosser-trend-nichts-dahinter\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.otto.de\/partnerprogramm\/voice-search-grosser-trend-nichts-dahinter\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.otto.de\/partnerprogramm\/voice-search-grosser-trend-nichts-dahinter\/#primaryimage","url":"https:\/\/www.otto.de\/partnerprogramm\/app\/uploads\/2018\/10\/pexels-photo-1072851.jpeg","contentUrl":"https:\/\/www.otto.de\/partnerprogramm\/app\/uploads\/2018\/10\/pexels-photo-1072851.jpeg","width":640,"height":426},{"@type":"BreadcrumbList","@id":"https:\/\/www.otto.de\/partnerprogramm\/voice-search-grosser-trend-nichts-dahinter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/edit.otto-partnerprogramm.de\/partnerprogramm\/"},{"@type":"ListItem","position":2,"name":"Voice Search: Gro\u00dfer Trend, nichts dahinter?"}]},{"@type":"WebSite","@id":"https:\/\/www.otto.de\/partnerprogramm\/#website","url":"https:\/\/www.otto.de\/partnerprogramm\/","name":"OTTO Affiliate","description":"Das OTTO Partnerprogramm","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.otto.de\/partnerprogramm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.otto.de\/partnerprogramm\/#\/schema\/person\/4c161909c66819493f845b52073d03b3","name":"Redaktion","url":"https:\/\/www.otto.de\/partnerprogramm\/author\/redaktion\/"}]}},"lang":"de","translations":{"de":1213},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.otto.de\/partnerprogramm\/wp-json\/wp\/v2\/posts\/1213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.otto.de\/partnerprogramm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.otto.de\/partnerprogramm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.otto.de\/partnerprogramm\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.otto.de\/partnerprogramm\/wp-json\/wp\/v2\/comments?post=1213"}],"version-history":[{"count":1,"href":"https:\/\/www.otto.de\/partnerprogramm\/wp-json\/wp\/v2\/posts\/1213\/revisions"}],"predecessor-version":[{"id":1215,"href":"https:\/\/www.otto.de\/partnerprogramm\/wp-json\/wp\/v2\/posts\/1213\/revisions\/1215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.otto.de\/partnerprogramm\/wp-json\/wp\/v2\/media\/1214"}],"wp:attachment":[{"href":"https:\/\/www.otto.de\/partnerprogramm\/wp-json\/wp\/v2\/media?parent=1213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.otto.de\/partnerprogramm\/wp-json\/wp\/v2\/categories?post=1213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.otto.de\/partnerprogramm\/wp-json\/wp\/v2\/tags?post=1213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}